{"id":149,"date":"2018-04-04T18:50:26","date_gmt":"2018-04-04T18:50:26","guid":{"rendered":"http:\/\/blog.continental.edu.pe\/preas-rioshullcas\/?p=149"},"modified":"2018-04-04T21:34:13","modified_gmt":"2018-04-04T21:34:13","slug":"reconocimiento-de-la-zona-de-muestreo","status":"publish","type":"post","link":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/noticias\/reconocimiento-de-la-zona-de-muestreo\/","title":{"rendered":"Estudiantes de Ingenier\u00eda Ambiental Reconocieron zonas del r\u00edo Shullcas  para iniciar la Actividad  del Muestreo"},"content":{"rendered":"<figure><a href=\"http:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-content\/uploads\/sites\/18\/2018\/04\/Actividad1.png\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" class=\"aligncenter\" src=\"http:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-content\/uploads\/sites\/18\/2018\/04\/Actividad2.png\" width=\"774\" height=\"452\" \/><img loading=\"lazy\" class=\"aligncenter\" title=\"actividad1\" src=\"http:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-content\/uploads\/sites\/18\/2018\/04\/Actividad1.png\" alt=\"\" width=\"774\" height=\"459\" \/><\/a><\/figure>\n<p>Los alumnos de Ingenier\u00eda Ambiental dieron por inicio a su primera actividad de Proyecci\u00f3n Social denominada \u201cPlan de Recuperaci\u00f3n Ecol\u00f3gica, Ambiental y Social de la Sub cuenca del r\u00edo Shullcas\u201d, con el fin hacer el reconocimiento de la zonas ubicados en la localidad de Acopalca, en la cual se har\u00e1n los estudios f\u00edsico qu\u00edmico y microbiol\u00f3gico del agua.Este proyecto\u00a0<strong> beneficiar\u00e1<\/strong> a los pobladores que viven cerca del curso del r\u00edo, como tambi\u00e9n a la <strong>recuperaci\u00f3n del ecosistema<\/strong> deteriorado por los m\u00faltiples problemas ambientales tales como deforestaci\u00f3n, extracci\u00f3n de agregados p\u00e9treos, residuos s\u00f3lidos, y entre otros.<\/p>\n<p>Al empezar el recorrido lograron observar un c\u00famulo de basura a escasos metros del r\u00edo y de la poblaci\u00f3n lo cual es un problema que no solo afecta a la salud de los pobladores si no tambi\u00e9n altera el ecosistema provocando una p\u00e9rdida de flora y fauna.<\/p>\n<p>El primer punto de muestreo se ubic\u00f3 a 100 metros del r\u00edo abajo del puente de Acopalca. En este punto observamos la uni\u00f3n de un r\u00edo m\u00e1s, el segundo punto de muestreo est\u00e1 ubicado a unos 150 metros r\u00edo abajo de la piscigranja, continuando con el recorrido podemos observar lo que es la deforestaci\u00f3n en varios puntos, tambi\u00e9n unos peque\u00f1os deslizamientos de tierra esto es a causa del exceso de lluvia, nuestro cuarto punto queda a 150 metro r\u00edo arriba del puente de Vilcacoto, por este tramo observamos c\u00f3mo los pobladores van al r\u00edo a lavar su ropa, realizan los pagapos, etc. Para finalizar llegamos al \u00faltimo\u00a0punto\u00a0ubicado a\u00a0100 metros r\u00edo arriba de los departamentos bella vista.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de Ingenier\u00eda Ambiental dieron por inicio a su primera actividad de Proyecci\u00f3n Social denominada \u201cPlan de Recuperaci\u00f3n Ecol\u00f3gica, Ambiental y Social de la Sub cuenca del r\u00edo Shullcas\u201d, con el fin hacer el reconocimiento de la zonas ubicados en la localidad de Acopalca, en la cual se har\u00e1n los estudios f\u00edsico qu\u00edmico y [&hellip;]<\/p>\n","protected":false},"author":60,"featured_media":188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[15,7],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/posts\/149"}],"collection":[{"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":27,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"predecessor-version":[{"id":197,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/posts\/149\/revisions\/197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/media\/188"}],"wp:attachment":[{"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.continental.edu.pe\/preas-rioshullcas\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}